{"id":15795,"date":"2025-05-14T15:11:26","date_gmt":"2025-05-14T13:11:26","guid":{"rendered":"https:\/\/aquavis.it\/psoreasy-autogel\/"},"modified":"2025-10-09T15:10:35","modified_gmt":"2025-10-09T13:10:35","slug":"psoreasy-autogel","status":"publish","type":"post","link":"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/","title":{"rendered":"PsorEasy Autogel (In vitro)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"15795\" class=\"elementor elementor-15795 elementor-14505\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"e-con-top elementor-element elementor-element-7c57376 e-flex e-con-boxed e-con e-parent\" data-id=\"7c57376\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1d1051 elementor-widget elementor-widget-heading\" data-id=\"d1d1051\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u00c9valuation in vitro<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec8fc48 e-con-full e-flex e-con e-child\" data-id=\"ec8fc48\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-90be515 e-con-full e-flex e-con e-child\" data-id=\"90be515\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47cdd18b elementor-widget elementor-widget-text-editor\" data-id=\"47cdd18b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pt-1 pb-4 aos-init aos-animate\" data-aos=\"fade-up\" data-aos-delay=\"200\">\n<div class=\"pt-1 pb-4 aos-init aos-animate\" data-aos=\"fade-up\" data-aos-delay=\"200\">\n<div class=\"pt-1 pb-4 aos-init aos-animate\" data-aos=\"fade-up\" data-aos-delay=\"200\">\n\nUne r\u00e9cente recherche men\u00e9e par une \u00e9quipe italo-espagnole a \u00e9tudi\u00e9 le potentiel de ce \u00ab fluide intelligent \u00bb dans la modulation des marqueurs mol\u00e9culaires du psoriasis en laboratoire.  \nLes r\u00e9sultats sugg\u00e8rent que l\u2019eau saline magn\u00e9tis\u00e9e, gr\u00e2ce \u00e0 l\u2019activation de l\u2019autophagie (un processus de r\u00e9g\u00e9n\u00e9ration cellulaire), peut <b>r\u00e9duire l\u2019inflammation<\/b> et <b>contrer la prolif\u00e9ration anormale des k\u00e9ratinocytes<\/b>, typique des l\u00e9sions psoriasiques.  \nUne \u00e9tude prometteuse qui ouvre la voie \u00e0 <b>de nouvelles strat\u00e9gies non pharmacologiques et durables<\/b> pour le traitement de cette pathologie cutan\u00e9e complexe.\n\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ffcdd4f e-con-full e-flex e-con e-child\" data-id=\"ffcdd4f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cad099 elementor-widget elementor-widget-image\" data-id=\"5cad099\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/94e1b430-218f-4c59-b64e-49407350f157.jpeg\" class=\"attachment-full size-full wp-image-16084\" alt=\"\" srcset=\"https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/94e1b430-218f-4c59-b64e-49407350f157.jpeg 1536w, https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/94e1b430-218f-4c59-b64e-49407350f157-300x200.jpeg 300w, https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/94e1b430-218f-4c59-b64e-49407350f157-1024x683.jpeg 1024w, https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/94e1b430-218f-4c59-b64e-49407350f157-768x512.jpeg 768w, https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/94e1b430-218f-4c59-b64e-49407350f157-500x333.jpeg 500w, https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/94e1b430-218f-4c59-b64e-49407350f157-1200x800.jpeg 1200w, https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/94e1b430-218f-4c59-b64e-49407350f157-480x320.jpeg 480w, https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/94e1b430-218f-4c59-b64e-49407350f157-240x160.jpeg 240w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f4a8cf elementor-widget elementor-widget-spacer\" data-id=\"8f4a8cf\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a58282 elementor-align-left elementor-tablet-align-center elementor-widget elementor-widget-reycore-button-skew\" data-id=\"1a58282\" data-element_type=\"widget\" data-widget_type=\"reycore-button-skew.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"rey-buttonSkew rey-buttonSkew--filled\" href=\"https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/NEL46_1_Minoretti.pdf\" target=\"_blank\">\n\t\t\n\t\t<span class=\"buttonSkew-left\"><\/span>\n\t\t<span class=\"buttonSkew-center\">\n\t\t\t<span>T\u00e9l\u00e9charger l\u2019article scientifique<\/span>\n\t\t<\/span>\n\t\t<span class=\"buttonSkew-right\"><\/span>\n\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2598de6 elementor-widget elementor-widget-spacer\" data-id=\"2598de6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"e-con-top elementor-element elementor-element-300404f e-flex e-con-boxed e-con e-parent\" data-id=\"300404f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9eb3f48 elementor-widget elementor-widget-reycore-product-grid\" data-id=\"9eb3f48\" data-element_type=\"widget\" data-widget_type=\"reycore-product-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"woocommerce rey-element reyEl-productGrid reyEl-productGrid--has-thumbs  \" data-qt=\"manual-selection\">\n\n\t\t<ul class=\"products  rey-wcGrid-default --skin-proto\" data-skin=\"--skin-proto\" data-cols=\"3\" data-cols-tablet=\"2\" data-cols-mobile=\"2\" data-discount-mobile-top=\"yes\" data-title-height=\"eq\" data-params=\"{&quot;equalize_selectors&quot;:[&quot;.woocommerce-loop-product__title&quot;]}\" >\n<li class=\"rey-swatches rey-swatches--stretch-labels product type-product post-15668 status-publish first instock product_cat-soin-de-la-peau has-post-thumbnail shipping-taxable purchasable product-type-simple is-animated --shadow- --shadow-h- --extraImg-slideshow --extraImg-mobile rey-wc-skin--proto rey-wc-loopAlign-left is-animated-entry --uncropped\" data-pid=\"15668\">\n\n\t<div class=\"rey-productInner --box-styler\"><div class=\"rey-productThumbnail\"><div class=\"splide \" data-arrows-id=\"__arrows-15668\"><div class=\"splide__track\"><div class=\"rey-productSlideshow splide__list\"><a href=\"https:\/\/aquavis.it\/fr\/prodotto\/psoreasy-autogel\/\" class=\"splide__slide\"><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/psoreasy-500x500.jpg\" class=\"rey-productThumbnail-extra\" alt=\"\" srcset=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/psoreasy-500x500.jpg 500w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/psoreasy-300x300.jpg 300w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/psoreasy-150x150.jpg 150w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/psoreasy-768x768.jpg 768w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/psoreasy-100x100.jpg 100w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/psoreasy.jpg 1000w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><a href=\"https:\/\/aquavis.it\/fr\/prodotto\/psoreasy-autogel\/\" class=\"splide__slide\"><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174136_8619526641435650_7962875409048773025_n-500x500.jpg\" class=\"rey-productThumbnail-extra\" alt=\"\" srcset=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174136_8619526641435650_7962875409048773025_n-500x500.jpg 500w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174136_8619526641435650_7962875409048773025_n-300x300.jpg 300w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174136_8619526641435650_7962875409048773025_n-150x150.jpg 150w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174136_8619526641435650_7962875409048773025_n-768x768.jpg 768w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174136_8619526641435650_7962875409048773025_n-100x100.jpg 100w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174136_8619526641435650_7962875409048773025_n-480x480.jpg 480w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174136_8619526641435650_7962875409048773025_n-240x240.jpg 240w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174136_8619526641435650_7962875409048773025_n.jpg 960w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><a href=\"https:\/\/aquavis.it\/fr\/prodotto\/psoreasy-autogel\/\" class=\"splide__slide\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174138_1233873654335423_4662917727923887388_n-500x500.jpg\" class=\"rey-productThumbnail-extra\" alt=\"\" srcset=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174138_1233873654335423_4662917727923887388_n-500x500.jpg 500w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174138_1233873654335423_4662917727923887388_n-300x300.jpg 300w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174138_1233873654335423_4662917727923887388_n-150x150.jpg 150w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174138_1233873654335423_4662917727923887388_n-768x768.jpg 768w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174138_1233873654335423_4662917727923887388_n-100x100.jpg 100w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174138_1233873654335423_4662917727923887388_n-480x480.jpg 480w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174138_1233873654335423_4662917727923887388_n-240x240.jpg 240w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468174138_1233873654335423_4662917727923887388_n.jpg 960w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><a href=\"https:\/\/aquavis.it\/fr\/prodotto\/psoreasy-autogel\/\" class=\"splide__slide\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468543281_1614991979398883_2748898632873318285_n-500x500.jpg\" class=\"rey-productThumbnail-extra\" alt=\"\" srcset=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468543281_1614991979398883_2748898632873318285_n-500x500.jpg 500w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468543281_1614991979398883_2748898632873318285_n-300x300.jpg 300w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468543281_1614991979398883_2748898632873318285_n-150x150.jpg 150w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468543281_1614991979398883_2748898632873318285_n-768x768.jpg 768w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468543281_1614991979398883_2748898632873318285_n-100x100.jpg 100w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468543281_1614991979398883_2748898632873318285_n-480x480.jpg 480w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468543281_1614991979398883_2748898632873318285_n-240x240.jpg 240w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468543281_1614991979398883_2748898632873318285_n.jpg 960w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><a href=\"https:\/\/aquavis.it\/fr\/prodotto\/psoreasy-autogel\/\" class=\"splide__slide\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434931_563790023113425_789093325309719428_n-500x500.jpg\" class=\"rey-productThumbnail-extra\" alt=\"\" srcset=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434931_563790023113425_789093325309719428_n-500x500.jpg 500w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434931_563790023113425_789093325309719428_n-300x300.jpg 300w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434931_563790023113425_789093325309719428_n-150x150.jpg 150w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434931_563790023113425_789093325309719428_n-768x768.jpg 768w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434931_563790023113425_789093325309719428_n-100x100.jpg 100w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434931_563790023113425_789093325309719428_n-480x480.jpg 480w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434931_563790023113425_789093325309719428_n-240x240.jpg 240w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434931_563790023113425_789093325309719428_n.jpg 960w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><a href=\"https:\/\/aquavis.it\/fr\/prodotto\/psoreasy-autogel\/\" class=\"splide__slide\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434405_555204483897559_3731556461850273079_n-500x500.jpg\" class=\"rey-productThumbnail-extra\" alt=\"\" srcset=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434405_555204483897559_3731556461850273079_n-500x500.jpg 500w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434405_555204483897559_3731556461850273079_n-300x300.jpg 300w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434405_555204483897559_3731556461850273079_n-150x150.jpg 150w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434405_555204483897559_3731556461850273079_n-768x768.jpg 768w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434405_555204483897559_3731556461850273079_n-100x100.jpg 100w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434405_555204483897559_3731556461850273079_n-480x480.jpg 480w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434405_555204483897559_3731556461850273079_n-240x240.jpg 240w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468434405_555204483897559_3731556461850273079_n.jpg 960w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><a href=\"https:\/\/aquavis.it\/fr\/prodotto\/psoreasy-autogel\/\" class=\"splide__slide\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468889401_603632815663556_7180839365044499942_n-500x500.jpg\" class=\"rey-productThumbnail-extra\" alt=\"\" srcset=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468889401_603632815663556_7180839365044499942_n-500x500.jpg 500w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468889401_603632815663556_7180839365044499942_n-300x300.jpg 300w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468889401_603632815663556_7180839365044499942_n-150x150.jpg 150w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468889401_603632815663556_7180839365044499942_n-768x768.jpg 768w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468889401_603632815663556_7180839365044499942_n-100x100.jpg 100w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468889401_603632815663556_7180839365044499942_n-480x480.jpg 480w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468889401_603632815663556_7180839365044499942_n-240x240.jpg 240w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/468889401_603632815663556_7180839365044499942_n.jpg 960w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><a href=\"https:\/\/aquavis.it\/fr\/prodotto\/psoreasy-autogel\/\" class=\"splide__slide\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/469119950_559411873490266_6105011123029865100_n-500x500.jpg\" class=\"rey-productThumbnail-extra\" alt=\"\" srcset=\"https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/469119950_559411873490266_6105011123029865100_n-500x500.jpg 500w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/469119950_559411873490266_6105011123029865100_n-300x300.jpg 300w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/469119950_559411873490266_6105011123029865100_n-150x150.jpg 150w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/469119950_559411873490266_6105011123029865100_n-768x768.jpg 768w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/469119950_559411873490266_6105011123029865100_n-100x100.jpg 100w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/469119950_559411873490266_6105011123029865100_n-480x480.jpg 480w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/469119950_559411873490266_6105011123029865100_n-240x240.jpg 240w, https:\/\/aquavis.it\/wp-content\/uploads\/2023\/11\/469119950_559411873490266_6105011123029865100_n.jpg 960w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div><div class=\"rey-productSlideshow-arrows __arrows-15668\"><div class=\"rey-arrowSvg rey-arrowSvg--left \" data-dir=\"<\"><svg aria-hidden=\"true\" role=\"img\" id=\"rey-icon-arrow-long-6a580fc6f41ca\" class=\"rey-icon rey-icon-arrow-long  --default\" viewbox=\"0 0 50 8\"><path d=\"M0.928904706,3.0387609 L44.0113745,3.0387609 L44.0113745,4.97541883 L0.928904706,4.97541883 C0.415884803,4.97541883 2.13162821e-14,4.54188318 2.13162821e-14,4.00708986 C2.13162821e-14,3.47229655 0.415884803,3.0387609 0.928904706,3.0387609 Z\" class=\"rey-arrowSvg-dash\" style=\"transform:var(--i-dsh-tr,initial);transition:var(--i-trs,initial);transform-origin:100% 50%;\"><\/path><path d=\"M49.6399545,3.16320794 L45.1502484,0.129110528 C45.0056033,0.0532149593 44.8474869,0.0092610397 44.685796,3.99680289e-14 C44.5479741,0.0112891909 44.4144881,0.0554642381 44.2956561,0.129110528 C44.0242223,0.2506013 43.8503957,0.531340097 43.8559745,0.839218433 L43.8559745,6.90741326 C43.8503957,7.21529159 44.0242223,7.49603039 44.2956561,7.61752116 C44.5594727,7.77895738 44.8864318,7.77895738 45.1502484,7.61752116 L49.6399545,4.58342375 C49.8682741,4.42554586 50.0055358,4.15892769 50.0055358,3.87331584 C50.0055358,3.587704 49.8682741,3.32108583 49.6399545,3.16320794 Z\"><\/path><\/svg><\/div><div class=\"rey-arrowSvg rey-arrowSvg--right \" data-dir=\">\"><svg aria-hidden=\"true\" role=\"img\" id=\"rey-icon-arrow-long-6a580fc6f41eb\" class=\"rey-icon rey-icon-arrow-long  --default\" viewbox=\"0 0 50 8\"><path d=\"M0.928904706,3.0387609 L44.0113745,3.0387609 L44.0113745,4.97541883 L0.928904706,4.97541883 C0.415884803,4.97541883 2.13162821e-14,4.54188318 2.13162821e-14,4.00708986 C2.13162821e-14,3.47229655 0.415884803,3.0387609 0.928904706,3.0387609 Z\" class=\"rey-arrowSvg-dash\" style=\"transform:var(--i-dsh-tr,initial);transition:var(--i-trs,initial);transform-origin:100% 50%;\"><\/path><path d=\"M49.6399545,3.16320794 L45.1502484,0.129110528 C45.0056033,0.0532149593 44.8474869,0.0092610397 44.685796,3.99680289e-14 C44.5479741,0.0112891909 44.4144881,0.0554642381 44.2956561,0.129110528 C44.0242223,0.2506013 43.8503957,0.531340097 43.8559745,0.839218433 L43.8559745,6.90741326 C43.8503957,7.21529159 44.0242223,7.49603039 44.2956561,7.61752116 C44.5594727,7.77895738 44.8864318,7.77895738 45.1502484,7.61752116 L49.6399545,4.58342375 C49.8682741,4.42554586 50.0055358,4.15892769 50.0055358,3.87331584 C50.0055358,3.587704 49.8682741,3.32108583 49.6399545,3.16320794 Z\"><\/path><\/svg><\/div><\/div><\/div><\/div><\/div>\t\t<div class=\"rey-loopDetails --padded\">\n\t\t<h2 class=\"woocommerce-loop-product__title\"><a href=\"https:\/\/aquavis.it\/fr\/prodotto\/psoreasy-autogel\/\">PsorEasy Autogel 75ml<\/a><\/h2>\t\t<a href=\"https:\/\/aquavis.it\/fr\/prodotto\/psoreasy-autogel\/\" class=\"woocommerce-product-details__short-description \">\n\t\t\tAvec Aquavis\u00ae, Extrait de Bardane, Aloe, Ur\u00e9e, Panth\u00e9nol, Prot\u00e9ines de Bl\u00e9, Glycine et Acide Lactique. Produit \u00e0 haute\u2026\t\t<\/a>\n\t\t<div class=\"__break\"><\/div><span class=\"price rey-loopPrice\"><span class=\"woocommerce-Price-amount amount\"><bdi>29,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/span>\t\t<div class=\"rey-loopButtons\">\n\t\t<a href=\"\/fr\/wp-json\/wp\/v2\/posts\/15795?add-to-cart=15668\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart rey-btn--primary\" data-product_id=\"15668\" data-product_sku=\"PSRS-1\" aria-label=\"Ajouter au panier\u00a0: &ldquo;PsorEasy Autogel 75ml&rdquo;\" rel=\"nofollow\" data-success_message=\"\u00ab\u00a0PsorEasy Autogel 75ml\u00a0\u00bb a \u00e9t\u00e9 ajout\u00e9 \u00e0 votre panier\" role=\"button\"><span class=\"__text\">Ajouter au panier<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_15668\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\n<\/li>\n\n<\/ul><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c9valuation in vitro Une r\u00e9cente recherche men\u00e9e par une \u00e9quipe italo-espagnole a \u00e9tudi\u00e9 le potentiel de ce \u00ab fluide intelligent [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":15796,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[355,356],"tags":[],"class_list":["post-15795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","category-test-clinici"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PsorEasy Autogel Aquavis : soulagement des peaux \u00e0 psoriasis<\/title>\n<meta name=\"description\" content=\"Gel \u00e0 haute concentration d\u2019Aquavis pour les peaux sujettes au psoriasis. Apaise, r\u00e9g\u00e9n\u00e8re et am\u00e9liore le confort cutan\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PsorEasy Autogel Aquavis : soulagement des peaux \u00e0 psoriasis\" \/>\n<meta property=\"og:description\" content=\"Gel \u00e0 haute concentration d\u2019Aquavis pour les peaux sujettes au psoriasis. Apaise, r\u00e9g\u00e9n\u00e8re et am\u00e9liore le confort cutan\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquavis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aquavis.it\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-14T13:11:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T13:10:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/test-psoriasi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"shiftcom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"shiftcom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/\",\"url\":\"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/\",\"name\":\"PsorEasy Autogel Aquavis : soulagement des peaux \u00e0 psoriasis\",\"isPartOf\":{\"@id\":\"https:\/\/aquavis.it\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/test-psoriasi.jpg\",\"datePublished\":\"2025-05-14T13:11:26+00:00\",\"dateModified\":\"2025-10-09T13:10:35+00:00\",\"author\":{\"@id\":\"https:\/\/aquavis.it\/fr\/#\/schema\/person\/8fd0cf191ee1e25de749f38f23c5658e\"},\"description\":\"Gel \u00e0 haute concentration d\u2019Aquavis pour les peaux sujettes au psoriasis. Apaise, r\u00e9g\u00e9n\u00e8re et am\u00e9liore le confort cutan\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/#primaryimage\",\"url\":\"https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/test-psoriasi.jpg\",\"contentUrl\":\"https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/test-psoriasi.jpg\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/aquavis.it\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PsorEasy Autogel (In vitro)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aquavis.it\/fr\/#website\",\"url\":\"https:\/\/aquavis.it\/fr\/\",\"name\":\"Aquavis\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aquavis.it\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/aquavis.it\/fr\/#\/schema\/person\/8fd0cf191ee1e25de749f38f23c5658e\",\"name\":\"shiftcom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/aquavis.it\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2399472286b327d1d0337b842579ee85?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2399472286b327d1d0337b842579ee85?s=96&d=mm&r=g\",\"caption\":\"shiftcom\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PsorEasy Autogel Aquavis : soulagement des peaux \u00e0 psoriasis","description":"Gel \u00e0 haute concentration d\u2019Aquavis pour les peaux sujettes au psoriasis. Apaise, r\u00e9g\u00e9n\u00e8re et am\u00e9liore le confort cutan\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/","og_locale":"fr_FR","og_type":"article","og_title":"PsorEasy Autogel Aquavis : soulagement des peaux \u00e0 psoriasis","og_description":"Gel \u00e0 haute concentration d\u2019Aquavis pour les peaux sujettes au psoriasis. Apaise, r\u00e9g\u00e9n\u00e8re et am\u00e9liore le confort cutan\u00e9.","og_url":"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/","og_site_name":"Aquavis","article_publisher":"https:\/\/www.facebook.com\/aquavis.it","article_published_time":"2025-05-14T13:11:26+00:00","article_modified_time":"2025-10-09T13:10:35+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/test-psoriasi.jpg","type":"image\/jpeg"}],"author":"shiftcom","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"shiftcom","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/","url":"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/","name":"PsorEasy Autogel Aquavis : soulagement des peaux \u00e0 psoriasis","isPartOf":{"@id":"https:\/\/aquavis.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/#primaryimage"},"image":{"@id":"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/#primaryimage"},"thumbnailUrl":"https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/test-psoriasi.jpg","datePublished":"2025-05-14T13:11:26+00:00","dateModified":"2025-10-09T13:10:35+00:00","author":{"@id":"https:\/\/aquavis.it\/fr\/#\/schema\/person\/8fd0cf191ee1e25de749f38f23c5658e"},"description":"Gel \u00e0 haute concentration d\u2019Aquavis pour les peaux sujettes au psoriasis. Apaise, r\u00e9g\u00e9n\u00e8re et am\u00e9liore le confort cutan\u00e9.","breadcrumb":{"@id":"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aquavis.it\/fr\/psoreasy-autogel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/#primaryimage","url":"https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/test-psoriasi.jpg","contentUrl":"https:\/\/aquavis.it\/wp-content\/uploads\/2025\/05\/test-psoriasi.jpg","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/aquavis.it\/fr\/psoreasy-autogel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aquavis.it\/fr\/"},{"@type":"ListItem","position":2,"name":"PsorEasy Autogel (In vitro)"}]},{"@type":"WebSite","@id":"https:\/\/aquavis.it\/fr\/#website","url":"https:\/\/aquavis.it\/fr\/","name":"Aquavis","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aquavis.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/aquavis.it\/fr\/#\/schema\/person\/8fd0cf191ee1e25de749f38f23c5658e","name":"shiftcom","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aquavis.it\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2399472286b327d1d0337b842579ee85?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2399472286b327d1d0337b842579ee85?s=96&d=mm&r=g","caption":"shiftcom"}}]}},"_links":{"self":[{"href":"https:\/\/aquavis.it\/fr\/wp-json\/wp\/v2\/posts\/15795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquavis.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aquavis.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aquavis.it\/fr\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/aquavis.it\/fr\/wp-json\/wp\/v2\/comments?post=15795"}],"version-history":[{"count":4,"href":"https:\/\/aquavis.it\/fr\/wp-json\/wp\/v2\/posts\/15795\/revisions"}],"predecessor-version":[{"id":16089,"href":"https:\/\/aquavis.it\/fr\/wp-json\/wp\/v2\/posts\/15795\/revisions\/16089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aquavis.it\/fr\/wp-json\/wp\/v2\/media\/15796"}],"wp:attachment":[{"href":"https:\/\/aquavis.it\/fr\/wp-json\/wp\/v2\/media?parent=15795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aquavis.it\/fr\/wp-json\/wp\/v2\/categories?post=15795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aquavis.it\/fr\/wp-json\/wp\/v2\/tags?post=15795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}